{"id":548,"date":"2021-04-24T16:03:54","date_gmt":"2021-04-24T19:03:54","guid":{"rendered":"https:\/\/www.rionortesaude.com.br\/blog\/?p=548"},"modified":"2021-04-20T10:36:18","modified_gmt":"2021-04-20T13:36:18","slug":"saiba-o-que-fazer-para-evitar-colicas-no-bebe","status":"publish","type":"post","link":"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/","title":{"rendered":"Saiba o que fazer para evitar c\u00f3licas no beb\u00ea"},"content":{"rendered":"<p class=\"estimated-read-time\">Tempo de leitura:<small> 5 minutos<\/small><\/p> \n<p>Para muitos papais e mam\u00e3es, o bem-estar de seus filhos, sem d\u00favidas, est\u00e1 no topo de sua lista de preocupa\u00e7\u00f5es. Por isso, quando o beb\u00ea tem crises de choro intensas, voc\u00ea vai querer saber do que se trata e o que pode fazer. Se, no entanto, o choro parece ser sem motivo e continua mesmo depois de verificar a fralda, aliment\u00e1-lo e confort\u00e1-lo da melhor maneira poss\u00edvel, pode ser um indicativo de que ele est\u00e1 com c\u00f3lica. Consequentemente, uma d\u00favida bastante comum que existe \u00e9 sobre como evitar e <strong>prevenir c\u00f3licas no beb\u00ea<\/strong>.<\/p>\n\n\n\n<p>Embora comuns, as c\u00f3licas s\u00e3o muito desconfort\u00e1veis, causando, al\u00e9m do choro constante, dor abdominal na crian\u00e7a. Portanto, uma consulta com um <a href=\"https:\/\/www.rionortesaude.com.br\/pediatra-madureira.php\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>pediatra em Madureira<\/strong> <\/a>deve ser agendada, para que voc\u00ea possa descobrir a melhor forma de preveni-las ou, ainda, alivi\u00e1-las.\u00a0<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_17 counter-hierarchy counter-decimal ez-toc-grey\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><a class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" style=\"display: none;\"><i class=\"ez-toc-glyphicon ez-toc-icon-toggle\"><\/i><\/a><\/span><\/div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1\"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/#Como_prevenir_colicas_no_bebe_confira_essas_dicas\" title=\"Como prevenir c\u00f3licas no beb\u00ea: confira essas dicas\">Como prevenir c\u00f3licas no beb\u00ea: confira essas dicas<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/#Ofereca_a_amamentacao_materna_exclusiva_durante_os_6_primeiros_meses\" title=\"Ofere\u00e7a a amamenta\u00e7\u00e3o materna exclusiva durante os 6 primeiros meses\">Ofere\u00e7a a amamenta\u00e7\u00e3o materna exclusiva durante os 6 primeiros meses<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/#Corrija_erros_na_pega\" title=\"Corrija erros na pega\">Corrija erros na pega<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/#Fique_de_olho_no_funcionamento_do_intestino_do_bebe\" title=\"Fique de olho no funcionamento do intestino do beb\u00ea\">Fique de olho no funcionamento do intestino do beb\u00ea<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/#Mude_sua_alimentacao\" title=\"Mude sua alimenta\u00e7\u00e3o\">Mude sua alimenta\u00e7\u00e3o<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/#Agende_uma_consulta_com_o_pediatra_em_Madureira\" title=\"Agende uma consulta com o pediatra em Madureira\">Agende uma consulta com o pediatra em Madureira<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Como_prevenir_colicas_no_bebe_confira_essas_dicas\"><\/span>Como prevenir c\u00f3licas no beb\u00ea: confira essas dicas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A seguir est\u00e3o algumas dicas para prevenir c\u00f3licas no beb\u00ea:<\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Ofereca_a_amamentacao_materna_exclusiva_durante_os_6_primeiros_meses\"><\/span>Ofere\u00e7a a amamenta\u00e7\u00e3o materna exclusiva durante os 6 primeiros meses<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Uma das grandes teorias por tr\u00e1s das c\u00f3licas nos beb\u00eas \u00e9 a justamente pela imaturidade intestinal nesta fase para digerir os alimentos e coordenar a peristalse. Assim, uma boa dica para prevenir e evitar c\u00f3licas no beb\u00ea \u00e9 justamente reduzir esse problema.&nbsp;<\/p>\n\n\n\n<p>Mas como fazer isso? Bom, a melhor forma \u00e9 oferecer o \u00fanico alimento que \u00e9 feito especialmente para ele. Isto \u00e9, o leite materno, que \u00e9 digerido mais facilmente. Como resultado, as chances do nen\u00e9m ter c\u00f3licas \u00e9 menor do que se ele ingerisse f\u00f3rmulas infantis ou leite de vaca.<\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Corrija_erros_na_pega\"><\/span>Corrija erros na pega<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Acredita-se que a c\u00f3lica possa ser causada pelo ar engolido pelo beb\u00ea durante as mamadas. Portanto, \u00e9 importante observar a forma como ele posiciona sua boca ao mamar, ou seja, a famosa pega, que pode aumentar o risco do intestino dele ficar cheio de ar e distendido, provocando maior desconforto.<\/p>\n\n\n\n<p>Garanta que, ao mamar, a barriga do beb\u00ea esteja encostada na barriga da m\u00e3e. A boca dele n\u00e3o deve cobrir apenas o mamilo, mas sim quase toda a ar\u00e9ola. Al\u00e9m disso, deve-se ficar atenta que os seus l\u00e1bios estejam evertidos (para fora, com boca \u201cde peixinho\u201d) e que ele realmente esteja sugando o leite e n\u00e3o apenas usando o bico do peito como chupeta.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"https:\/\/lh6.googleusercontent.com\/w44NeR3I0DKfDpC4V6CGk9zl-AI3erDw2gJW6Ip7dDHglZluKZtMNBVdu9XPHdRix9SK8cmJvLTfq9QNDf0RojVRM1B6DzmtEvasDKRFC_AF_lRGz8y184UjHm9UVL7AOcNsqNU6\" alt=\"\"\/><\/figure>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Fique_de_olho_no_funcionamento_do_intestino_do_bebe\"><\/span>Fique de olho no funcionamento do intestino do beb\u00ea<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Quando o beb\u00ea passa muitos dias sem evacuar ou mostra desconforto e esfor\u00e7o ao faz\u00ea-lo, o risco dele ter mais c\u00f3licas \u00e9 maior. Isso ocorre principalmente devido aos movimentos intestinais excessivos, que podem ser um mecanismo para tornar a sa\u00edda das fezes mais f\u00e1cil.&nbsp;<\/p>\n\n\n\n<p>Portanto, caso voc\u00ea perceba que o seu filho apresenta fezes ressecadas ou faz esfor\u00e7o na hora de evacuar, converse com o pediatra em Madureira, para saber o que voc\u00ea pode fazer para melhorar o funcionamento intestinal do seu beb\u00ea.<\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Mude_sua_alimentacao\"><\/span>Mude sua alimenta\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Embora ainda n\u00e3o haja uma comprova\u00e7\u00e3o cient\u00edfica da rela\u00e7\u00e3o direta entre a alimenta\u00e7\u00e3o da m\u00e3e e o surgimento de <strong>c\u00f3licas nos beb\u00eas<\/strong>, muitas mam\u00e3es observam essa associa\u00e7\u00e3o no dia a dia.<\/p>\n\n\n\n<p>Por isso, acredita-se que alguns ingredientes alimentares que passam para o leite materno podem causar c\u00f3licas na crian\u00e7a, como especiarias, cafe\u00edna ou \u00e1lcool. Assim, cortar esses alimentos e bebidas de sua dieta \u00e9 uma forma que elas encontraram de prevenir e evitar c\u00f3licas nos beb\u00eas que amamentam.<\/p>\n\n\n\n<p>Al\u00e9m disso, devido \u00e0 intoler\u00e2ncia tempor\u00e1ria a essas subst\u00e2ncias secretadas pelo leite materno, a prote\u00edna do leite pode causar c\u00f3licas em alguns beb\u00eas. Assim, remover todos os latic\u00ednios da dieta pode funcionar. Neste caso, a m\u00e3e deve consultar o m\u00e9dico para decidir sobre a dieta correta e saud\u00e1vel sem latic\u00ednios, que n\u00e3o resultar\u00e1 em defici\u00eancia de c\u00e1lcio.<\/p>\n\n\n\n<p>Outra medida que \u00e0s vezes \u00e9 recomend\u00e1vel, \u00e9 evitar o chocolate. Em alguns casos, al\u00e9rgenos como nozes precisam ser removidos da dieta. Alimentos que produzem g\u00e1s, como repolho, br\u00f3colis e feij\u00e3o tamb\u00e9m podem ser evitados.&nbsp;<\/p>\n\n\n\n<p>Se a m\u00e3e estiver amamentando o beb\u00ea, mas estiver tomando medicamentos, ela deve verificar se o medicamento n\u00e3o passa para o leite materno e irrita o trato digestivo do beb\u00ea.<\/p>\n\n\n\n<h2><span class=\"ez-toc-section\" id=\"Agende_uma_consulta_com_o_pediatra_em_Madureira\"><\/span>Agende uma consulta com o pediatra em Madureira<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Se o choro do seu beb\u00ea persistir e nada parece ajudar, pode ser hora de agendar uma consulta com um pediatra em Madureira. Voc\u00ea poder\u00e1 descrever o choro, como a sua dura\u00e7\u00e3o, intensidade, padr\u00e3o, qualquer varia\u00e7\u00e3o e quaisquer sintomas associados ao m\u00e9dico e ele poder\u00e1 examinar o seu filho.<\/p>\n\n\n\n<p>Dessa forma, ser\u00e1 poss\u00edvel determinar se o beb\u00ea tem c\u00f3lica mesmo, descartando qualquer outra causa potencial de choro excessivo, ou identificar alguma condi\u00e7\u00e3o m\u00e9dica subjacente, tais como refluxo, infec\u00e7\u00e3o ou alergia ao leite que possa estar desencadeando o choro.<\/p>\n\n\n\n<p>Portanto, agende agora mesmo uma consulta com o pediatra em Madureira! Na cl\u00ednica Rio Norte Sa\u00fade, al\u00e9m da consulta, os <a href=\"https:\/\/www.rionortesaude.com.br\/blog\/exames-que-precisam-ser-feitos-durante-e-apos-a-gravidez-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">exames do seu beb\u00ea<\/a> podem ser realizados com o m\u00e1ximo conforto e seguran\u00e7a. Para isso, estamos seguindo todas as recomenda\u00e7\u00f5es da Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) e do Minist\u00e9rio da Sa\u00fade, a fim de evitar a propaga\u00e7\u00e3o do coronav\u00edrus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><small> 5 minutos<\/small> Para muitos papais e mam\u00e3es, o bem-estar de seus filhos, sem d\u00favidas, est\u00e1 no topo de sua lista de preocupa\u00e7\u00f5es. Por isso, quando o beb\u00ea tem crises de choro intensas, voc\u00ea vai querer saber do que se trata e o que pode fazer. Se, no entanto, o choro parece ser sem motivo e continua mesmo depois de verificar a fralda, aliment\u00e1-lo e confort\u00e1-lo da melhor maneira poss\u00edvel, pode ser um indicativo de que ele est\u00e1 com c\u00f3lica. Consequentemente, uma d\u00favida bastante comum <a href=\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/\" class=\"more-link\"><span>Continue lendo<\/span>\u2192<\/a><\/p>\n","protected":false},"author":4,"featured_media":549,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Saiba o que fazer para evitar c\u00f3licas no beb\u00ea | Blog<\/title>\n<meta name=\"description\" content=\"Para muitos papais e mam\u00e3es, o bem-estar de seus filhos, sem d\u00favidas, est\u00e1 no topo de sua lista de preocupa\u00e7\u00f5es. Por isso, quando o beb\u00ea tem crises de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saiba o que fazer para evitar c\u00f3licas no beb\u00ea | Blog\" \/>\n<meta property=\"og:description\" content=\"Para muitos papais e mam\u00e3es, o bem-estar de seus filhos, sem d\u00favidas, est\u00e1 no topo de sua lista de preocupa\u00e7\u00f5es. Por isso, quando o beb\u00ea tem crises de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-24T19:03:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-20T13:36:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rionortesaude.com.br\/blog\/wp-content\/uploads\/2021\/04\/4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1326\" \/>\n\t<meta property=\"og:image:height\" content=\"928\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"4 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/#organization\",\"name\":\"Rio norte Sa\\u00fade\",\"url\":\"https:\/\/www.rionortesaude.com.br\/blog\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.rionortesaude.com.br\/blog\/wp-content\/uploads\/2019\/01\/logo-1.png\",\"width\":391,\"height\":100,\"caption\":\"Rio norte Sa\\u00fade\"},\"image\":{\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/#website\",\"url\":\"https:\/\/www.rionortesaude.com.br\/blog\/\",\"name\":\"Blog\",\"description\":\"Aqui voc\\u00ea encontrar\\u00e1 artigos relativos a area da sa\\u00fade, bem como, dicas, tutoriais, para se manter saud\\u00e1vel.\",\"publisher\":{\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.rionortesaude.com.br\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.rionortesaude.com.br\/blog\/wp-content\/uploads\/2021\/04\/4.png\",\"width\":1326,\"height\":928,\"caption\":\"beb\\u00ea com c\\u00f3licas\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/#webpage\",\"url\":\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/\",\"name\":\"Saiba o que fazer para evitar c\\u00f3licas no beb\\u00ea | Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/#primaryimage\"},\"datePublished\":\"2021-04-24T19:03:54+00:00\",\"dateModified\":\"2021-04-20T13:36:18+00:00\",\"description\":\"Para muitos papais e mam\\u00e3es, o bem-estar de seus filhos, sem d\\u00favidas, est\\u00e1 no topo de sua lista de preocupa\\u00e7\\u00f5es. Por isso, quando o beb\\u00ea tem crises de\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/#\/schema\/person\/8feaea37ecbe6680acf9abef81a45886\"},\"headline\":\"Saiba o que fazer para evitar c\\u00f3licas no beb\\u00ea\",\"datePublished\":\"2021-04-24T19:03:54+00:00\",\"dateModified\":\"2021-04-20T13:36:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/#webpage\"},\"publisher\":{\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/saiba-o-que-fazer-para-evitar-colicas-no-bebe\/#primaryimage\"},\"articleSection\":\"Pediatria\",\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/#\/schema\/person\/8feaea37ecbe6680acf9abef81a45886\",\"name\":\"Rio Norte Sa\\u00fade\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.rionortesaude.com.br\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6ae7fe7287eab8f000807cb44bb40849?s=96&d=mm&r=g\",\"caption\":\"Rio Norte Sa\\u00fade\"},\"description\":\"Criada com o objetivo de oferecer consultas e servi\\u00e7os a pre\\u00e7os acess\\u00edveis, a Rio Norte Sa\\u00fade tem a proposta de disponibilizar um atendimento diferenciado e de qualidade para aqueles que n\\u00e3o possuem planos de sa\\u00fade. Amparo, apoio, carinho, cuidado e humaniza\\u00e7\\u00e3o s\\u00e3o elementos que comp\\u00f5em os pilares da cl\\u00ednica. A Rio Norte conta ainda com profissionais altamente capacitados e equipe multidisciplinar s\\u00e9ria e \\u00e9tica que funcionam como parte da sua identidade. Localizada em um lugar de f\\u00e1cil acesso, no centro de Madureira - Zona Norte do Rio, a cl\\u00ednica conta com diversas especialidades para atender pacientes de todas as idades e com os mais variados casos cl\\u00ednicos e exames laboratoriais. Ginecologia Pediatria Cardiologia Cl\\u00ednica M\\u00e9dica Gastroenterologia Endocrinologia Dermatologia Nutri\\u00e7\\u00e3o Ortopedia Urologia Angiologia Proctologia Atendimento ao Idoso Psicologia Neurologia Obstetra\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.rionortesaude.com.br\/blog\/wp-json\/wp\/v2\/posts\/548"}],"collection":[{"href":"https:\/\/www.rionortesaude.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rionortesaude.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rionortesaude.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rionortesaude.com.br\/blog\/wp-json\/wp\/v2\/comments?post=548"}],"version-history":[{"count":1,"href":"https:\/\/www.rionortesaude.com.br\/blog\/wp-json\/wp\/v2\/posts\/548\/revisions"}],"predecessor-version":[{"id":550,"href":"https:\/\/www.rionortesaude.com.br\/blog\/wp-json\/wp\/v2\/posts\/548\/revisions\/550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rionortesaude.com.br\/blog\/wp-json\/wp\/v2\/media\/549"}],"wp:attachment":[{"href":"https:\/\/www.rionortesaude.com.br\/blog\/wp-json\/wp\/v2\/media?parent=548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rionortesaude.com.br\/blog\/wp-json\/wp\/v2\/categories?post=548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rionortesaude.com.br\/blog\/wp-json\/wp\/v2\/tags?post=548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}